{"id":6704,"date":"2025-10-28T18:24:23","date_gmt":"2025-10-28T18:24:23","guid":{"rendered":"https:\/\/bahamasound.com\/?post_type=product&#038;p=6704"},"modified":"2025-10-28T18:24:25","modified_gmt":"2025-10-28T18:24:25","slug":"rossetti-paracho-bajo-sexto-gloss-finish-acoustic-guitar","status":"publish","type":"product","link":"https:\/\/bahamasound.com\/index.php\/product\/rossetti-paracho-bajo-sexto-gloss-finish-acoustic-guitar\/","title":{"rendered":"Rossetti Paracho Bajo Sexto, Gloss Finish Acoustic Guitar"},"content":{"rendered":"<p>Rossetti Paracho Bajo Sexto, Gloss Finish Acoustic Guitar<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rossetti Paracho Bajo Sexto, Gloss Finish Acoustic Guitar<\/p>\n","protected":false},"featured_media":6734,"template":"","meta":[],"product_brand":[],"product_cat":[188,17],"product_tag":[],"class_list":{"0":"post-6704","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-acoustic-guitars","7":"product_cat-guitar-bass","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rossetti Paracho Bajo Sexto, Gloss Finish Acoustic Guitar - BAHAMASOUND | MUSIC INSTRUMENTS | MUSIC ACCESSORIES<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bahamasound.com\/index.php\/product\/rossetti-paracho-bajo-sexto-gloss-finish-acoustic-guitar\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rossetti Paracho Bajo Sexto, Gloss Finish Acoustic Guitar - BAHAMASOUND | MUSIC INSTRUMENTS | MUSIC ACCESSORIES\" \/>\n<meta property=\"og:description\" content=\"Rossetti Paracho Bajo Sexto, Gloss Finish Acoustic Guitar\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bahamasound.com\/index.php\/product\/rossetti-paracho-bajo-sexto-gloss-finish-acoustic-guitar\/\" \/>\n<meta property=\"og:site_name\" content=\"BAHAMASOUND | MUSIC INSTRUMENTS | MUSIC ACCESSORIES\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-28T18:24:25+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bahamasound.com\/index.php\/product\/rossetti-paracho-bajo-sexto-gloss-finish-acoustic-guitar\/\",\"url\":\"https:\/\/bahamasound.com\/index.php\/product\/rossetti-paracho-bajo-sexto-gloss-finish-acoustic-guitar\/\",\"name\":\"Rossetti Paracho Bajo Sexto, Gloss Finish Acoustic Guitar - BAHAMASOUND | MUSIC INSTRUMENTS | MUSIC ACCESSORIES\",\"isPartOf\":{\"@id\":\"https:\/\/bahamasound.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/bahamasound.com\/index.php\/product\/rossetti-paracho-bajo-sexto-gloss-finish-acoustic-guitar\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/bahamasound.com\/index.php\/product\/rossetti-paracho-bajo-sexto-gloss-finish-acoustic-guitar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/bahamasound.com\/wp-content\/uploads\/2025\/10\/BSE.jpg\",\"datePublished\":\"2025-10-28T18:24:23+00:00\",\"dateModified\":\"2025-10-28T18:24:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/bahamasound.com\/index.php\/product\/rossetti-paracho-bajo-sexto-gloss-finish-acoustic-guitar\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bahamasound.com\/index.php\/product\/rossetti-paracho-bajo-sexto-gloss-finish-acoustic-guitar\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/bahamasound.com\/index.php\/product\/rossetti-paracho-bajo-sexto-gloss-finish-acoustic-guitar\/#primaryimage\",\"url\":\"https:\/\/bahamasound.com\/wp-content\/uploads\/2025\/10\/BSE.jpg\",\"contentUrl\":\"https:\/\/bahamasound.com\/wp-content\/uploads\/2025\/10\/BSE.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bahamasound.com\/index.php\/product\/rossetti-paracho-bajo-sexto-gloss-finish-acoustic-guitar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/bahamasound.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\/\/bahamasound.com\/index.php\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rossetti Paracho Bajo Sexto, Gloss Finish Acoustic Guitar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bahamasound.com\/#website\",\"url\":\"https:\/\/bahamasound.com\/\",\"name\":\"BAHAMASOUND | MUSIC INSTRUMENTS | MUSIC ACCESSORIES\",\"description\":\"Electric Guitars | Acoustic Guitars | Amplifiers | Digital Pianos\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bahamasound.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rossetti Paracho Bajo Sexto, Gloss Finish Acoustic Guitar - BAHAMASOUND | MUSIC INSTRUMENTS | MUSIC ACCESSORIES","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bahamasound.com\/index.php\/product\/rossetti-paracho-bajo-sexto-gloss-finish-acoustic-guitar\/","og_locale":"en_US","og_type":"article","og_title":"Rossetti Paracho Bajo Sexto, Gloss Finish Acoustic Guitar - BAHAMASOUND | MUSIC INSTRUMENTS | MUSIC ACCESSORIES","og_description":"Rossetti Paracho Bajo Sexto, Gloss Finish Acoustic Guitar","og_url":"https:\/\/bahamasound.com\/index.php\/product\/rossetti-paracho-bajo-sexto-gloss-finish-acoustic-guitar\/","og_site_name":"BAHAMASOUND | MUSIC INSTRUMENTS | MUSIC ACCESSORIES","article_modified_time":"2025-10-28T18:24:25+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bahamasound.com\/index.php\/product\/rossetti-paracho-bajo-sexto-gloss-finish-acoustic-guitar\/","url":"https:\/\/bahamasound.com\/index.php\/product\/rossetti-paracho-bajo-sexto-gloss-finish-acoustic-guitar\/","name":"Rossetti Paracho Bajo Sexto, Gloss Finish Acoustic Guitar - BAHAMASOUND | MUSIC INSTRUMENTS | MUSIC ACCESSORIES","isPartOf":{"@id":"https:\/\/bahamasound.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bahamasound.com\/index.php\/product\/rossetti-paracho-bajo-sexto-gloss-finish-acoustic-guitar\/#primaryimage"},"image":{"@id":"https:\/\/bahamasound.com\/index.php\/product\/rossetti-paracho-bajo-sexto-gloss-finish-acoustic-guitar\/#primaryimage"},"thumbnailUrl":"https:\/\/bahamasound.com\/wp-content\/uploads\/2025\/10\/BSE.jpg","datePublished":"2025-10-28T18:24:23+00:00","dateModified":"2025-10-28T18:24:25+00:00","breadcrumb":{"@id":"https:\/\/bahamasound.com\/index.php\/product\/rossetti-paracho-bajo-sexto-gloss-finish-acoustic-guitar\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bahamasound.com\/index.php\/product\/rossetti-paracho-bajo-sexto-gloss-finish-acoustic-guitar\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bahamasound.com\/index.php\/product\/rossetti-paracho-bajo-sexto-gloss-finish-acoustic-guitar\/#primaryimage","url":"https:\/\/bahamasound.com\/wp-content\/uploads\/2025\/10\/BSE.jpg","contentUrl":"https:\/\/bahamasound.com\/wp-content\/uploads\/2025\/10\/BSE.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/bahamasound.com\/index.php\/product\/rossetti-paracho-bajo-sexto-gloss-finish-acoustic-guitar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bahamasound.com\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/bahamasound.com\/index.php\/shop\/"},{"@type":"ListItem","position":3,"name":"Rossetti Paracho Bajo Sexto, Gloss Finish Acoustic Guitar"}]},{"@type":"WebSite","@id":"https:\/\/bahamasound.com\/#website","url":"https:\/\/bahamasound.com\/","name":"BAHAMASOUND | MUSIC INSTRUMENTS | MUSIC ACCESSORIES","description":"Electric Guitars | Acoustic Guitars | Amplifiers | Digital Pianos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bahamasound.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/bahamasound.com\/index.php\/wp-json\/wp\/v2\/product\/6704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bahamasound.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bahamasound.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bahamasound.com\/index.php\/wp-json\/wp\/v2\/media\/6734"}],"wp:attachment":[{"href":"https:\/\/bahamasound.com\/index.php\/wp-json\/wp\/v2\/media?parent=6704"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bahamasound.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=6704"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bahamasound.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=6704"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bahamasound.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=6704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}